{"id":378,"date":"2026-09-02T19:03:31","date_gmt":"2026-09-02T17:03:31","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/belle-dys-trail-bailleul-59-2026-09-19\/"},"modified":"2026-09-02T19:19:04","modified_gmt":"2026-09-02T17:19:04","slug":"belle-dys-trail-bailleul-59-2026-09-19","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/belle-dys-trail-bailleul-59-2026-09-19\/","title":{"rendered":"Belle Dys Trail \u2013 Bailleul (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>TRAIL \u00b7 Bailleul (59) \u00b7 10,7 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[159],"class_list":["post-378","course","type-course","status-publish","hentry","course_discipline-trail"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=378"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}