{"id":397,"date":"2026-09-02T19:03:32","date_gmt":"2026-09-02T17:03:32","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/les-foulees-levalloises-leval-59-2026-09-20\/"},"modified":"2026-09-02T19:19:05","modified_gmt":"2026-09-02T17:19:05","slug":"les-foulees-levalloises-leval-59-2026-09-20","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/les-foulees-levalloises-leval-59-2026-09-20\/","title":{"rendered":"Les foul\u00e9es levalloises \u2013 Leval (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>RUNNING \u00b7 Leval (59) \u00b7 84,0 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[156],"class_list":["post-397","course","type-course","status-publish","hentry","course_discipline-running"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}