{"id":453,"date":"2026-09-02T19:03:34","date_gmt":"2026-09-02T17:03:34","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/la-jar-etoilee-roncq-59-2026-10-10\/"},"modified":"2026-09-02T19:19:05","modified_gmt":"2026-09-02T17:19:05","slug":"la-jar-etoilee-roncq-59-2026-10-10","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/la-jar-etoilee-roncq-59-2026-10-10\/","title":{"rendered":"La Jar \u00e9toil\u00e9e \u2013 Roncq (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>MARCHE \u00b7 Roncq (59) \u00b7 46,4 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[157],"class_list":["post-453","course","type-course","status-publish","hentry","course_discipline-marche"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=453"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}