{"id":455,"date":"2026-09-02T19:03:34","date_gmt":"2026-09-02T17:03:34","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/flowerun-by-ieseg-lille-59-2026-10-10\/"},"modified":"2026-09-02T19:19:05","modified_gmt":"2026-09-02T17:19:05","slug":"flowerun-by-ieseg-lille-59-2026-10-10","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/flowerun-by-ieseg-lille-59-2026-10-10\/","title":{"rendered":"Flo\u2019WeRun by IESEG \u2013 Lille (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>RUNNING \u00b7 Lille (59)<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[156],"class_list":["post-455","course","type-course","status-publish","hentry","course_discipline-running"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}