{"id":522,"date":"2026-09-02T19:03:38","date_gmt":"2026-09-02T17:03:38","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/trail-de-la-vallee-de-la-thure-by-night-cousolre-59-2026-11-07\/"},"modified":"2026-09-02T19:19:06","modified_gmt":"2026-09-02T17:19:06","slug":"trail-de-la-vallee-de-la-thure-by-night-cousolre-59-2026-11-07","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/trail-de-la-vallee-de-la-thure-by-night-cousolre-59-2026-11-07\/","title":{"rendered":"Trail de la vall\u00e9e de la Thure by night \u2013 Cousolre (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>TRAIL \u00b7 59<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[159],"class_list":["post-522","course","type-course","status-publish","hentry","course_discipline-trail"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=522"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}