{"id":526,"date":"2026-09-02T19:03:38","date_gmt":"2026-09-02T17:03:38","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/monts-et-merveilles-boeschepe-59-2026-11-08\/"},"modified":"2026-09-02T19:19:06","modified_gmt":"2026-09-02T17:19:06","slug":"monts-et-merveilles-boeschepe-59-2026-11-08","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/monts-et-merveilles-boeschepe-59-2026-11-08\/","title":{"rendered":"Monts et merveilles \u2013 Boesch\u00e8pe (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>RUNNING \u00b7 Boeschepe (59) \u00b7 41,7 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[156],"class_list":["post-526","course","type-course","status-publish","hentry","course_discipline-running"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=526"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}