{"id":553,"date":"2026-09-02T19:03:39","date_gmt":"2026-09-02T17:03:39","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/cross-de-la-sensee-fechain-59-2026-11-22\/"},"modified":"2026-09-02T19:19:07","modified_gmt":"2026-09-02T17:19:07","slug":"cross-de-la-sensee-fechain-59-2026-11-22","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/cross-de-la-sensee-fechain-59-2026-11-22\/","title":{"rendered":"Cross de la Sens\u00e9e \u2013 F\u00e9chain (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>RUNNING \u00b7 F\u00e9chain (59) \u00b7 39,4 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[156],"class_list":["post-553","course","type-course","status-publish","hentry","course_discipline-running"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=553"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}