{"id":557,"date":"2026-09-02T19:03:39","date_gmt":"2026-09-02T17:03:39","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/trail-nocturne-de-la-saint-nicolas-henin-beaumont-62-2026-11-28\/"},"modified":"2026-09-02T19:19:07","modified_gmt":"2026-09-02T17:19:07","slug":"trail-nocturne-de-la-saint-nicolas-henin-beaumont-62-2026-11-28","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/trail-nocturne-de-la-saint-nicolas-henin-beaumont-62-2026-11-28\/","title":{"rendered":"Trail nocturne de la Saint-Nicolas \u2013 He\u0301nin-Beaumont (62)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>TRAIL \u00b7 62<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[159],"class_list":["post-557","course","type-course","status-publish","hentry","course_discipline-trail"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}