{"id":562,"date":"2026-09-02T19:03:39","date_gmt":"2026-09-02T17:03:39","guid":{"rendered":"https:\/\/www.trippsport.fr\/blog\/courses\/course-des-clochers-villers-sire-nicole-59-2026-11-29\/"},"modified":"2026-09-02T19:19:07","modified_gmt":"2026-09-02T17:19:07","slug":"course-des-clochers-villers-sire-nicole-59-2026-11-29","status":"publish","type":"course","link":"https:\/\/www.trippsport.fr\/blog\/courses\/course-des-clochers-villers-sire-nicole-59-2026-11-29\/","title":{"rendered":"Course des clochers \u2013 Villers-Sire-Nicole (59)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>RUNNING \u00b7 Villers-Sire-Nicole (59) \u00b7 92,9 km d\u2019Aix-Noulette<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"course_discipline":[156],"class_list":["post-562","course","type-course","status-publish","hentry","course_discipline-running"],"_links":{"self":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course\/562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/types\/course"}],"wp:attachment":[{"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/media?parent=562"}],"wp:term":[{"taxonomy":"course_discipline","embeddable":true,"href":"https:\/\/www.trippsport.fr\/blog\/wp-json\/wp\/v2\/course_discipline?post=562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}